{"id":829,"date":"2023-09-04T12:24:27","date_gmt":"2023-09-04T12:24:27","guid":{"rendered":"http:\/\/xcare-demo.pbminfotech.com\/demo1\/?page_id=1467"},"modified":"2025-12-11T17:51:51","modified_gmt":"2025-12-11T17:51:51","slug":"homepage-02","status":"publish","type":"page","link":"https:\/\/lamddk.com\/en\/?page_id=820","title":{"rendered":"Lamddk"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"829\" class=\"elementor elementor-829\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-2f9bfd3 elementor-section-content-middle elementor-section-stretched elementor-section-full_width pbmit-bg-image-over-color pbmit-col-stretched-none elementor-section-height-default elementor-section-height-default\" data-id=\"2f9bfd3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f994908 pbmit-bg-color-yes pbmit-elementor-bg-color-globalcolor pbmit-bg-color-over-image\" data-id=\"f994908\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-1697ade elementor-section-content-middle pbmit-text-color-white pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1697ade\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d9c4a84 pbmit-bg-color-over-image\" data-id=\"d9c4a84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01e2cbf elementor-widget elementor-widget-pbmit_icon_heading\" data-id=\"01e2cbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pbmit-ihbox pbmit-ihbox-style-13\"><div class=\"pbmit-ihbox-box\">\r\n\t<div class=\"pbmit-ihbox-icon\"><div class=\"pbmit-ihbox-icon-wrapper pbmit-icon-type-icon\"><svg class=\"e-font-icon-svg e-fas-moon\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M283.211 512c78.962 0 151.079-35.925 198.857-94.792 7.068-8.708-.639-21.43-11.562-19.35-124.203 23.654-238.262-71.576-238.262-196.954 0-72.222 38.662-138.635 101.498-174.394 9.686-5.512 7.25-20.197-3.756-22.23A258.156 258.156 0 0 0 283.211 0c-141.309 0-256 114.511-256 256 0 141.309 114.511 256 256 256z\"><\/path><\/svg><\/div><\/div>\t<div class=\"pbmit-ihbox-contents\">\r\n\t\t\t\t\t<h2 class=\"pbmit-element-title\">Garde de nuit :<br> +216 98 529 338<\/h2>\t\t\t\t\t<\/div>\r\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-43ced0f pbmit-bg-color-over-image\" data-id=\"43ced0f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-593ebbd elementor-widget elementor-widget-pbmit_spinner_box_element\" data-id=\"593ebbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_spinner_box_element.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t\r\n\t\t<div class=\"pbminfotech-element\r\n\t\t\tpbminfotech-element-spinner-box\t\t\tpbmit-element-spinner-box-style-1\t\t\tpbmit-element-viewtype-row-column\t\t\tpbmit-element-column-three\t\t\tpbmit-element-sticky-carousel-false\t\t\tpbmit-element-caroursel-dot-false\t\t\tpbmit-infinite-scroll-no\t\t\tpbmit-infinite-scroll-button-no\t\t\t\t\t\t\t\t\t\t\t\t\"\r\n\r\n\t\t\tdata-cpt=\"spinner-box\"\r\n\t\t\tdata-totalpagination=\"1\"\r\n\t\t\tdata-style=\"1\"\r\n\t\t\tdata-show=\"3\"\r\n\t\t\tdata-columns=\"3\"\r\n\t\t\tdata-loop=\"false\"\r\n\t\t\tdata-autoplay=\"false\"\r\n\t\t\tdata-center=\"false\"\r\n\t\t\tdata-nav=\"false\"\r\n\t\t\tdata-dots=\"false\"\r\n\t\t\tdata-reverse=\"false\"\r\n\t\t\tdata-speed=\"1000\"\r\n\t\t\tdata-delay=\"4000\"\r\n\t\t\tdata-margin=\"\"\r\n\t\t\tdata-show-portion=\"false\">\r\n\r\n\t\t\t<div class=\"pbmit-element-inner\">\r\n\t\t\r\n\r\n\t\t\r\n\t\t<div class=\"pbmit-element-posts-wrapper\">\r\n\r\n\t\t\t<div class=\"pbmit-spinner pbmit-spinner-box-style-1\">\r\n<a class=\"pbmit-scroll-section\" href = \"https:\/\/lamddk.com\/service\/domaines-dactivites\/\" >\r\n\t<div class=\"pbmit-ihbox-box\">\r\n\t\t<div class=\"pbmit-ihbox-icon\"><svg class=\"e-font-icon-svg e-fas-level-down-alt\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.553 392.331L209.587 504.334c-9.485 10.214-25.676 10.229-35.174 0L70.438 392.331C56.232 377.031 67.062 352 88.025 352H152V80H68.024a11.996 11.996 0 0 1-8.485-3.515l-56-56C-4.021 12.926 1.333 0 12.024 0H208c13.255 0 24 10.745 24 24v328h63.966c20.878 0 31.851 24.969 17.587 40.331z\"><\/path><\/svg><\/div>\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" viewBox=\"0 0 200 200\">\r\n\t\t\t<defs>\r\n\t\t\t\t<path d=\"M0, 100a100, 100 0 1, 0 200, 0a100, 100 0 1, 0 -200, 0\" id=\"txt-path\"><\/path>\r\n\t\t\t<\/defs>\r\n\t\t\t<circle cx=\"150\" cy=\"100\" r=\"75\" fill=\"none\"\/>\r\n\t\t\t<text font-size=\"15\" font-family=\"Sora,sans-serif\" font-weight=\"500\">\r\n\t\t\t\t<textPath startOffset=\"0\" xlink:href=\"#txt-path\">NOS PRESTATIONS. NOS PRESTATIONS. NOS PRESTATIONS .<\/textPath>\r\n\t\t\t<\/text>\r\n\t\t<\/svg>\r\n\t<\/div>\r\n<\/a><\/div>\r\n\t\t <\/div>\r\n\r\n\t\t\t\t\t<\/div><!-- .pbmit-element-inner -->\r\n\t\t<\/div><!-- .pbminfotech-element -->\r\n\r\n\t\t\t\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bf97222 pbmit-bg-color-over-image\" data-id=\"bf97222\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37751b1 pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37751b1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33ab2f2 pbmit-bg-color-over-image\" data-id=\"33ab2f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c031095 elementor-widget elementor-widget-spacer\" data-id=\"c031095\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7799531 pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7799531\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d7a56f3 pbmit-bg-color-over-image\" data-id=\"d7a56f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ad13f1 pbmit-animation-none elementor-widget elementor-widget-image\" data-id=\"2ad13f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"236\" height=\"300\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/LOGO_TUNAC_1-0124_page-0001-removebg-preview-236x300.png\" class=\"attachment-medium size-medium wp-image-4830\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/LOGO_TUNAC_1-0124_page-0001-removebg-preview-236x300.png 236w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/LOGO_TUNAC_1-0124_page-0001-removebg-preview-9x12.png 9w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/LOGO_TUNAC_1-0124_page-0001-removebg-preview.png 384w\" sizes=\"(max-width: 236px) 100vw, 236px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbc55e0 pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbc55e0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd851de pbmit-bg-color-over-image\" data-id=\"bd851de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6ebf26 elementor-widget elementor-widget-spacer\" data-id=\"e6ebf26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bff4add pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bff4add\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c6b24d pbmit-bg-color-over-image\" data-id=\"8c6b24d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3efc58e elementor-widget elementor-widget-text-editor\" data-id=\"3efc58e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\">Notre laboratoire de biologie m\u00e9dicale est accr\u00e9dit\u00e9 par le Conseil National<br \/>d\u2019Accr\u00e9ditation TUNAC sous le certificat n\u00b0 1-0124, valable du 29\/10\/2025 au 28\/10\/2030.<br \/>Cette accr\u00e9ditation confirme la qualit\u00e9, la fiabilit\u00e9 et la conformit\u00e9 de nos analyses selon<br \/>les normes internationales.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-860b187 pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"860b187\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61700ec pbmit-bg-color-over-image\" data-id=\"61700ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6b3fad elementor-widget elementor-widget-spacer\" data-id=\"f6b3fad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72f02be pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72f02be\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5d4e0f7 pbmit-bg-color-over-image\" data-id=\"5d4e0f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eabac65 pbmit-animation-none elementor-widget elementor-widget-image\" data-id=\"eabac65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"746\" height=\"1024\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-AR-1_page-0001-746x1024.jpg\" class=\"attachment-large size-large wp-image-4827\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-AR-1_page-0001-746x1024.jpg 746w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-AR-1_page-0001-219x300.jpg 219w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-AR-1_page-0001-768x1054.jpg 768w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-AR-1_page-0001-1119x1536.jpg 1119w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-AR-1_page-0001-9x12.jpg 9w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-AR-1_page-0001.jpg 1280w\" sizes=\"(max-width: 746px) 100vw, 746px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-941c6ae pbmit-bg-color-over-image\" data-id=\"941c6ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-171e917 pbmit-animation-none elementor-widget elementor-widget-image\" data-id=\"171e917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"744\" height=\"1024\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-FR_page-0001-744x1024.jpg\" class=\"attachment-large size-large wp-image-4828\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-FR_page-0001-744x1024.jpg 744w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-FR_page-0001-218x300.jpg 218w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-FR_page-0001-768x1057.jpg 768w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-FR_page-0001-1116x1536.jpg 1116w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-FR_page-0001-9x12.jpg 9w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-FR_page-0001.jpg 1275w\" sizes=\"(max-width: 744px) 100vw, 744px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8821792 pbmit-bg-color-over-image\" data-id=\"8821792\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e5b53a pbmit-animation-none elementor-widget elementor-widget-image\" data-id=\"4e5b53a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"746\" height=\"1024\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-EN_page-0001-746x1024.jpg\" class=\"attachment-large size-large wp-image-4829\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-EN_page-0001-746x1024.jpg 746w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-EN_page-0001-219x300.jpg 219w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-EN_page-0001-768x1054.jpg 768w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-EN_page-0001-1119x1536.jpg 1119w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-EN_page-0001-9x12.jpg 9w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/11\/Certificat-EN_page-0001.jpg 1280w\" sizes=\"(max-width: 746px) 100vw, 746px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-968e348 pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"968e348\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81209e9 pbmit-bg-color-over-image\" data-id=\"81209e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e83dca elementor-widget elementor-widget-spacer\" data-id=\"0e83dca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bcf954 pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bcf954\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b79a240 pbmit-bg-color-over-image\" data-id=\"b79a240\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8280277 elementor-widget elementor-widget-spacer\" data-id=\"8280277\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ef8037 pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ef8037\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cad9e14 pbmit-bg-color-over-image\" data-id=\"cad9e14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-582d5f8 elementor-widget elementor-widget-spacer\" data-id=\"582d5f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5e40b3 pbmit-col-stretched-both elementor-section-full_width elementor-hidden-mobile pbmit-bg-color-over-image elementor-section-height-default elementor-section-height-default\" data-id=\"f5e40b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28ab4f4 pbmit-bg-color-over-image\" data-id=\"28ab4f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f530fc3 elementor-widget__width-inherit elementor-hidden-mobile elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"f530fc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-caba248 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-07a0241 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-d180597 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-4df0d5e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-f110347 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-4f1e2be swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive pr\u00e9c\u00e9dente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive suivante\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc53a16 pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc53a16\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c18dac pbmit-bg-color-over-image\" data-id=\"2c18dac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbd0254 elementor-widget elementor-widget-spacer\" data-id=\"bbd0254\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d99298 pbmit-col-stretched-both elementor-section-full_width elementor-hidden-mobile pbmit-bg-color-over-image elementor-section-height-default elementor-section-height-default\" data-id=\"3d99298\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce36802 pbmit-bg-color-over-image\" data-id=\"ce36802\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-beb1967 pbmit-col-stretched-both elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet pbmit-bg-color-over-image elementor-section-height-default elementor-section-height-default\" data-id=\"beb1967\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff7dd20 pbmit-bg-color-over-image\" data-id=\"ff7dd20\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c67be50 elementor-widget__width-inherit elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"c67be50\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-caba248 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-ff57358 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-f54a654 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-cf05463 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-d180597 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive pr\u00e9c\u00e9dente\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Diapositive suivante\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c4f9506 pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c4f9506\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a2fcf8 pbmit-bg-color-over-image\" data-id=\"8a2fcf8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70051c6 elementor-widget elementor-widget-spacer\" data-id=\"70051c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-baadf1e elementor-section-full_width pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-height-default elementor-section-height-default\" data-id=\"baadf1e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a6ff4e0 pbmit-bg-color-over-image\" data-id=\"a6ff4e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8b5a3e elementor-widget elementor-widget-pbmit_icon_heading\" data-id=\"e8b5a3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pbmit-ihbox pbmit-ihbox-style-15\"><div class=\"pbmit-ihbox-box\">\r\n\t<div class=\"pbmit-icon-wrap d-flex align-items-center\">\r\n\t\t<div class=\"pbmit-ihbox-icon\"><div class=\"pbmit-ihbox-icon-wrapper pbmit-icon-type-icon\"><i class=\"mdi mdi-access-time\"><\/i><\/div><\/div>\t\t\t\t\t<\/div>\r\n\t<h2 class=\"pbmit-element-title\">Horaires<\/h2>\t<div class=\"pbmit-content-wrapper\">\r\n\t\t\t\t<div class=\"pbmit-heading-desc\">Lundi - Vendredi : 7h00 - 19h00<br>\nSamedi : 7h00 - 17h00<br>\nDimanche: 8h00 - 14h<br>\nGarde de nuit\/urgences: 24\/7<\/div>\t<\/div>\t\r\n<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-42f6901 pbmit-bg-color-over-image\" data-id=\"42f6901\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88304c4 elementor-widget elementor-widget-pbmit_icon_heading\" data-id=\"88304c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pbmit-ihbox pbmit-ihbox-style-15\"><div class=\"pbmit-ihbox-box\">\r\n\t<div class=\"pbmit-icon-wrap d-flex align-items-center\">\r\n\t\t<div class=\"pbmit-ihbox-icon\"><div class=\"pbmit-ihbox-icon-wrapper pbmit-icon-type-icon\"><i class=\"sgicon sgicon-Message\"><\/i><\/div><\/div>\t\t\t\t\t<\/div>\r\n\t<h2 class=\"pbmit-element-title\">Contact<\/h2>\t<div class=\"pbmit-content-wrapper\">\r\n\t\t\t\t<div class=\"pbmit-heading-desc\">Tel:\n+216 96 669 338 \/ 216 70 288 684 <br>\nEmail: lamdderouiche@gmail.com contact@lamddk.com<br>\n\nSite Web: www.lamddk.com<\/div>\t<\/div>\t\r\n<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2df8c7c pbmit-bg-color-over-image\" data-id=\"2df8c7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1180ca elementor-widget elementor-widget-pbmit_icon_heading\" data-id=\"f1180ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pbmit-ihbox pbmit-ihbox-style-15\"><div class=\"pbmit-ihbox-box\">\r\n\t<div class=\"pbmit-icon-wrap d-flex align-items-center\">\r\n\t\t<div class=\"pbmit-ihbox-icon\"><div class=\"pbmit-ihbox-icon-wrapper pbmit-icon-type-icon\"><i class=\"pbmit-xcare-icon pbmit-xcare-icon-hospital-bed\"><\/i><\/div><\/div>\t\t\t\t\t<\/div>\r\n\t<h2 class=\"pbmit-element-title\">Garde de nuit<\/h2>\t<div class=\"pbmit-content-wrapper\">\r\n\t\t\t\t<div class=\"pbmit-heading-desc\">Nous offrons un service de garde de nuit assurant les urgences.<br> (service disponible 24\/7)<\/div>\t<\/div>\t\r\n<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48f4c4f pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48f4c4f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-84e5983 pbmit-bg-color-over-image\" data-id=\"84e5983\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cff23f0 pbmit-bg-color-over-image\" data-id=\"cff23f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-caf1a09 elementor-section-full_width pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-height-default elementor-section-height-default\" data-id=\"caf1a09\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-704aa7a pbmit-bg-color-over-image\" data-id=\"704aa7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1011e5 pbmit-animation-none elementor-widget elementor-widget-image\" data-id=\"f1011e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/1343APRESPROPOS-scaled-scaled.webp\" class=\"attachment-full size-full wp-image-2923\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/1343APRESPROPOS-scaled-scaled.webp 2560w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/1343APRESPROPOS-scaled-300x225.webp 300w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/1343APRESPROPOS-scaled-1024x768.webp 1024w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/1343APRESPROPOS-scaled-768x576.webp 768w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/1343APRESPROPOS-scaled-1536x1152.webp 1536w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/1343APRESPROPOS-scaled-2048x1536.webp 2048w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/1343APRESPROPOS-scaled-16x12.webp 16w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3677219 pbmit-bg-color-over-image\" data-id=\"3677219\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ac9acf elementor-widget elementor-widget-heading\" data-id=\"8ac9acf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mot du biologiste<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f750c2 elementor-widget elementor-widget-text-editor\" data-id=\"7f750c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\">\nL&rsquo;accr\u00e9ditation de notre laboratoire iso 15189 n&rsquo;est pas une simple distinction, elle confirme notre engagement \u00e0 offrir des r\u00e9sultats pr\u00e9cis, un service performant et un accompagnement de qualit\u00e9 \u00e0 nos patients, prescripteurs et partenaires.\n<\/p>\n\n<p style=\"text-align: justify;\">\nL&rsquo;obtention de cette accr\u00e9ditation vient couronner un travail rigoureux men\u00e9 par l&rsquo;ensemble de notre \u00e9quipe, mobilis\u00e9e autour de l&rsquo;am\u00e9lioration continue, de la s\u00e9curit\u00e9 du patient et du respect des bonnes pratiques professionnelles.\n<\/p>\n\n<p style=\"text-align: justify;\">\nNous continuerons \u00e0 renforcer nos processus et \u00e0 d\u00e9velopper nos comp\u00e9tences pour garantir un niveau de qualit\u00e9 constamment \u00e9lev\u00e9, au service de votre sant\u00e9 et de votre confiance.\n<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92685b7 pbmit-btn-shape-round pbmit-btn-color-globalcolor pbmit-btn-hover-color-blackish pbmit-btn-style-flat elementor-widget elementor-widget-button\" data-id=\"92685b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/a-propos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrez notre laboratoire<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f6661d pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f6661d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-321b4bf pbmit-bg-color-over-image\" data-id=\"321b4bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7878c7 elementor-widget elementor-widget-spacer\" data-id=\"b7878c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6b166c elementor-section-stretched pbmit-bg-color-yes pbmit-elementor-bg-color-globalcolor pbmit-text-color-white pbmit-extend-animation elementor-section-height-full pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"b6b166c\" data-element_type=\"section\" data-e-type=\"section\" id=\"Pbmit-service-scroll\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b958cf4 pbmit-bg-color-over-image\" data-id=\"b958cf4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77b9f2f elementor-widget elementor-widget-pbmit_service_element\" data-id=\"77b9f2f\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"nospres\" data-widget_type=\"pbmit_service_element.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t\r\n\t\t<div class=\"pbminfotech-element\r\n\t\t\tpbminfotech-element-service\t\t\tpbmit-element-service-style-5\t\t\tpbmit-element-viewtype-row-column\t\t\tpbmit-element-column-three\t\t\tpbmit-element-sticky-carousel-false\t\t\tpbmit-element-caroursel-dot-false\t\t\tpbmit-infinite-scroll-no\t\t\tpbmit-infinite-scroll-button-no\t\t\tpbminfotech-gap-default\t\t\t\t\t\t\t\t\t\"\r\n\r\n\t\t\tdata-cpt=\"service\"\r\n\t\t\tdata-totalpagination=\"2\"\r\n\t\t\tdata-style=\"5\"\r\n\t\t\tdata-show=\"10\"\r\n\t\t\tdata-columns=\"3\"\r\n\t\t\tdata-loop=\"false\"\r\n\t\t\tdata-autoplay=\"false\"\r\n\t\t\tdata-center=\"false\"\r\n\t\t\tdata-nav=\"false\"\r\n\t\t\tdata-dots=\"false\"\r\n\t\t\tdata-reverse=\"false\"\r\n\t\t\tdata-speed=\"1000\"\r\n\t\t\tdata-delay=\"4000\"\r\n\t\t\tdata-margin=\"default\"\r\n\t\t\tdata-show-portion=\"false\">\r\n\r\n\t\t\t<div class=\"pbmit-element-inner\">\r\n\t\t\r\n\r\n\t\t\t\t\t<div class=\"pbmit-ele-header-area\">\r\n\t\t\t\t\t<div class=\"pbmit-heading-subheading  animation-style4\"><h2 class=\"pbmit-element-title\">\r\n\t\t\t\r\n\t\t\t\tNos Prestations\r\n\t\t\t\r\n\t\t\t<\/h2>\r\n\t\t<div class=\"pbmit-heading-desc\">Notre laboratoire est \u00e9quip\u00e9 des derni\u00e8res technologies et notre \u00e9quipe\nde professionnels qualifi\u00e9s est d\u00e9di\u00e9e \u00e0 fournir des r\u00e9sultats pr\u00e9cis et rapides.<\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t<div class=\"pbmit-infinite-scroll-data\">{\"cpt\":\"service\",\"style\":\"5\",\"show\":10,\"order\":\"DESC\",\"orderby\":\"date\"}<\/div>\r\n\t\t\t\t<div class=\"pbmit-element-posts-wrapper row multi-columns-row  \">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-main-hover-slider d-flex align-items-center\">\r\n\t\t\t\t\t\t\t<div class=\"swiper-hover-slide-images col-md-5 col-lg-5\">\r\n\t\t\t\t\t\t\t\t<div class=\"swiper pbmit-hover-image\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/areas-of-activity-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/IMG_1360-1130x1070.jpg\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbmit-service-icon elementor-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/samples-taken-in-the-laboratory\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/4554545-2-1130x1070.jpg\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/4554545-2-1130x1070.jpg 1130w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/4554545-2-12x12.jpg 12w\" sizes=\"(max-width: 1130px) 100vw, 1130px\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbmit-service-icon elementor-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"pbmit-xcare-icon pbmit-xcare-icon-elbow\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/home-direct-debit\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/pvt-a-domicile-1130x1070.webp\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbmit-service-icon elementor-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/day-care-service\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/ddk-1130x1070.png\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbmit-service-icon elementor-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/sampling-manual\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1063\" height=\"1008\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/manuel-de-pvt-cover_Plan-de-travail-1_Plan-de-travail-1-e1739895106712-1-e1741879729669.png\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/manuel-de-pvt-cover_Plan-de-travail-1_Plan-de-travail-1-e1739895106712-1-e1741879729669.png 1063w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/manuel-de-pvt-cover_Plan-de-travail-1_Plan-de-travail-1-e1739895106712-1-e1741879729669-300x284.png 300w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/manuel-de-pvt-cover_Plan-de-travail-1_Plan-de-travail-1-e1739895106712-1-e1741879729669-1024x971.png 1024w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/manuel-de-pvt-cover_Plan-de-travail-1_Plan-de-travail-1-e1739895106712-1-e1741879729669-768x728.png 768w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/manuel-de-pvt-cover_Plan-de-travail-1_Plan-de-travail-1-e1739895106712-1-e1741879729669-13x12.png 13w\" sizes=\"(max-width: 1063px) 100vw, 1063px\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbmit-service-icon elementor-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/list-of-tests\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/liste-2-1130x1070.jpg\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/liste-2-1130x1070.jpg 1130w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/liste-2-12x12.jpg 12w\" sizes=\"(max-width: 1130px) 100vw, 1130px\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbmit-service-icon elementor-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/list-of-urgent-examinations-and-turnaround-times\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/urgenceCentrif-1130x1070.png\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbmit-service-icon elementor-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/subcontracted-examinations-subcontracted-laboratories\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/SOUS-TRT-1130x1070.jpg\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbmit-service-icon elementor-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/consultancy-service\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/CONCEIL-1130x1070.jpg\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbmit-service-icon elementor-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/approved-bodies\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/conv-1130x1070.jpg\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbmit-service-icon elementor-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class= \"swiper-hover-slide-nav col-md-7 col-lg-7\">\r\n\t\t\t\t\t\t\t\t<ul class=\"pbmit-hover-inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-title-data-hover\" data-text =\"Domaines d\u2019activit\u00e9s\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/areas-of-activity-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/IMG_1360-1130x1070.jpg\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-text-content d-flex align-items-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbminfotech-box-number\">01<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pbmit-title-inner\" href=\"https:\/\/lamddk.com\/en\/service\/areas-of-activity-2\/\"><span>Domaines d\u2019activit\u00e9s<\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-service-btn\"><a href=\"https:\/\/lamddk.com\/en\/service\/areas-of-activity-2\/\"><span class=\"pbmit-button-icon-wrapper\"><span class=\"pbmit-button-icon\"><i class=\"pbmit-base-icon-black-arrow-1\"><\/i><\/span><\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><a class=\"pbmit-link\" href=\"https:\/\/lamddk.com\/en\/service\/areas-of-activity-2\/\"><\/a><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-title-data-hover\" data-text =\"Pr\u00e9l\u00e8vements au sein du laboratoire\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/samples-taken-in-the-laboratory\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/4554545-2-1130x1070.jpg\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/4554545-2-1130x1070.jpg 1130w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/4554545-2-12x12.jpg 12w\" sizes=\"(max-width: 1130px) 100vw, 1130px\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-text-content d-flex align-items-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbminfotech-box-number\">02<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pbmit-title-inner\" href=\"https:\/\/lamddk.com\/en\/service\/samples-taken-in-the-laboratory\/\"><span>Pr\u00e9l\u00e8vements au sein du laboratoire<\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-service-btn\"><a href=\"https:\/\/lamddk.com\/en\/service\/samples-taken-in-the-laboratory\/\"><span class=\"pbmit-button-icon-wrapper\"><span class=\"pbmit-button-icon\"><i class=\"pbmit-base-icon-black-arrow-1\"><\/i><\/span><\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><a class=\"pbmit-link\" href=\"https:\/\/lamddk.com\/en\/service\/samples-taken-in-the-laboratory\/\"><\/a><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-title-data-hover\" data-text =\"Pr\u00e9l\u00e8vement \u00e0 domicile\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/home-direct-debit\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/pvt-a-domicile-1130x1070.webp\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-text-content d-flex align-items-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbminfotech-box-number\">03<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pbmit-title-inner\" href=\"https:\/\/lamddk.com\/en\/service\/home-direct-debit\/\"><span>Pr\u00e9l\u00e8vement \u00e0 domicile<\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-service-btn\"><a href=\"https:\/\/lamddk.com\/en\/service\/home-direct-debit\/\"><span class=\"pbmit-button-icon-wrapper\"><span class=\"pbmit-button-icon\"><i class=\"pbmit-base-icon-black-arrow-1\"><\/i><\/span><\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><a class=\"pbmit-link\" href=\"https:\/\/lamddk.com\/en\/service\/home-direct-debit\/\"><\/a><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-title-data-hover\" data-text =\"Service de garde\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/day-care-service\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/ddk-1130x1070.png\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-text-content d-flex align-items-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbminfotech-box-number\">04<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pbmit-title-inner\" href=\"https:\/\/lamddk.com\/en\/service\/day-care-service\/\"><span>Service de garde<\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-service-btn\"><a href=\"https:\/\/lamddk.com\/en\/service\/day-care-service\/\"><span class=\"pbmit-button-icon-wrapper\"><span class=\"pbmit-button-icon\"><i class=\"pbmit-base-icon-black-arrow-1\"><\/i><\/span><\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><a class=\"pbmit-link\" href=\"https:\/\/lamddk.com\/en\/service\/day-care-service\/\"><\/a><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-title-data-hover\" data-text =\"Manuel de pr\u00e9l\u00e8vement\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/sampling-manual\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1063\" height=\"1008\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/manuel-de-pvt-cover_Plan-de-travail-1_Plan-de-travail-1-e1739895106712-1-e1741879729669.png\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/manuel-de-pvt-cover_Plan-de-travail-1_Plan-de-travail-1-e1739895106712-1-e1741879729669.png 1063w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/manuel-de-pvt-cover_Plan-de-travail-1_Plan-de-travail-1-e1739895106712-1-e1741879729669-300x284.png 300w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/manuel-de-pvt-cover_Plan-de-travail-1_Plan-de-travail-1-e1739895106712-1-e1741879729669-1024x971.png 1024w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/manuel-de-pvt-cover_Plan-de-travail-1_Plan-de-travail-1-e1739895106712-1-e1741879729669-768x728.png 768w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/manuel-de-pvt-cover_Plan-de-travail-1_Plan-de-travail-1-e1739895106712-1-e1741879729669-13x12.png 13w\" sizes=\"(max-width: 1063px) 100vw, 1063px\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-text-content d-flex align-items-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbminfotech-box-number\">05<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pbmit-title-inner\" href=\"https:\/\/lamddk.com\/en\/service\/sampling-manual\/\"><span>Manuel de pr\u00e9l\u00e8vement<\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-service-btn\"><a href=\"https:\/\/lamddk.com\/en\/service\/sampling-manual\/\"><span class=\"pbmit-button-icon-wrapper\"><span class=\"pbmit-button-icon\"><i class=\"pbmit-base-icon-black-arrow-1\"><\/i><\/span><\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><a class=\"pbmit-link\" href=\"https:\/\/lamddk.com\/en\/service\/sampling-manual\/\"><\/a><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-title-data-hover\" data-text =\"LISTE DES EXAMENS\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/list-of-tests\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/liste-2-1130x1070.jpg\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/liste-2-1130x1070.jpg 1130w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/liste-2-12x12.jpg 12w\" sizes=\"(max-width: 1130px) 100vw, 1130px\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-text-content d-flex align-items-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbminfotech-box-number\">06<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pbmit-title-inner\" href=\"https:\/\/lamddk.com\/en\/service\/list-of-tests\/\"><span>LISTE DES EXAMENS<\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-service-btn\"><a href=\"https:\/\/lamddk.com\/en\/service\/list-of-tests\/\"><span class=\"pbmit-button-icon-wrapper\"><span class=\"pbmit-button-icon\"><i class=\"pbmit-base-icon-black-arrow-1\"><\/i><\/span><\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><a class=\"pbmit-link\" href=\"https:\/\/lamddk.com\/en\/service\/list-of-tests\/\"><\/a><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-title-data-hover\" data-text =\"Liste des examens urgents et d\u00e9lais d\u2019ex\u00e9cution\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/list-of-urgent-examinations-and-turnaround-times\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/urgenceCentrif-1130x1070.png\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-text-content d-flex align-items-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbminfotech-box-number\">07<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pbmit-title-inner\" href=\"https:\/\/lamddk.com\/en\/service\/list-of-urgent-examinations-and-turnaround-times\/\"><span>Liste des examens urgents et d\u00e9lais d\u2019ex\u00e9cution<\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-service-btn\"><a href=\"https:\/\/lamddk.com\/en\/service\/list-of-urgent-examinations-and-turnaround-times\/\"><span class=\"pbmit-button-icon-wrapper\"><span class=\"pbmit-button-icon\"><i class=\"pbmit-base-icon-black-arrow-1\"><\/i><\/span><\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><a class=\"pbmit-link\" href=\"https:\/\/lamddk.com\/en\/service\/list-of-urgent-examinations-and-turnaround-times\/\"><\/a><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-title-data-hover\" data-text =\"Examens sous-trait\u00e9s \/ Laboratoires sous traitants\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/subcontracted-examinations-subcontracted-laboratories\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/SOUS-TRT-1130x1070.jpg\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-text-content d-flex align-items-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbminfotech-box-number\">08<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pbmit-title-inner\" href=\"https:\/\/lamddk.com\/en\/service\/subcontracted-examinations-subcontracted-laboratories\/\"><span>Examens sous-trait\u00e9s \/ Laboratoires sous traitants<\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-service-btn\"><a href=\"https:\/\/lamddk.com\/en\/service\/subcontracted-examinations-subcontracted-laboratories\/\"><span class=\"pbmit-button-icon-wrapper\"><span class=\"pbmit-button-icon\"><i class=\"pbmit-base-icon-black-arrow-1\"><\/i><\/span><\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><a class=\"pbmit-link\" href=\"https:\/\/lamddk.com\/en\/service\/subcontracted-examinations-subcontracted-laboratories\/\"><\/a><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-title-data-hover\" data-text =\"Prestation conseil\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/consultancy-service\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/CONCEIL-1130x1070.jpg\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-text-content d-flex align-items-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbminfotech-box-number\">09<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pbmit-title-inner\" href=\"https:\/\/lamddk.com\/en\/service\/consultancy-service\/\"><span>Prestation conseil<\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-service-btn\"><a href=\"https:\/\/lamddk.com\/en\/service\/consultancy-service\/\"><span class=\"pbmit-button-icon-wrapper\"><span class=\"pbmit-button-icon\"><i class=\"pbmit-base-icon-black-arrow-1\"><\/i><\/span><\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><a class=\"pbmit-link\" href=\"https:\/\/lamddk.com\/en\/service\/consultancy-service\/\"><\/a><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t<li>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-title-data-hover\" data-text =\"Organismes conventionn\u00e9s\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><a href=\"https:\/\/lamddk.com\/en\/service\/approved-bodies\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1130\" height=\"1070\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/01\/conv-1130x1070.jpg\" class=\"attachment-pbmit-img-1130x1070 size-pbmit-img-1130x1070 wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-text-content d-flex align-items-center\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pbminfotech-box-number\">10<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pbmit-title-inner\" href=\"https:\/\/lamddk.com\/en\/service\/approved-bodies\/\"><span>Organismes conventionn\u00e9s<\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pbmit-service-btn\"><a href=\"https:\/\/lamddk.com\/en\/service\/approved-bodies\/\"><span class=\"pbmit-button-icon-wrapper\"><span class=\"pbmit-button-icon\"><i class=\"pbmit-base-icon-black-arrow-1\"><\/i><\/span><\/span><\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/div><a class=\"pbmit-link\" href=\"https:\/\/lamddk.com\/en\/service\/approved-bodies\/\"><\/a><\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t<\/div> <!-- .pbmit-element-posts-wrapper -->\r\n\t\t\t \r\n\r\n\t\t\t\r\n\t\t\r\n\t\t\r\n\t\t\t\t\t<\/div><!-- .pbmit-element-inner -->\r\n\t\t<\/div><!-- .pbminfotech-element -->\r\n\r\n\t\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8582f5 elementor-section-full_width pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-height-default elementor-section-height-default\" data-id=\"e8582f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a55c10 pbmit-bg-color-over-image\" data-id=\"6a55c10\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6be184 elementor-widget elementor-widget-pbmit_heading\" data-id=\"a6be184\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"pbmit-heading-subheading pbmit-reverse-heading-yes animation-style4\"><h2 class=\"pbmit-element-title\">\r\n\t\t\t\r\n\t\t\t\tCe Qui Nous Distingue\r\n\t\t\t\r\n\t\t\t<\/h2>\r\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c28b77 pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c28b77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-52be493 pbmit-bg-color-over-image\" data-id=\"52be493\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce168bb elementor-widget elementor-widget-pbmit_icon_heading\" data-id=\"ce168bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pbmit-ihbox pbmit-ihbox-style-16\"><div class=\"pbmit-ihbox-icon\"><div class=\"pbmit-ihbox-icon-wrapper pbmit-icon-type-icon\"><svg class=\"e-font-icon-svg e-fas-compress-arrows-alt\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M200 288H88c-21.4 0-32.1 25.8-17 41l32.9 31-99.2 99.3c-6.2 6.2-6.2 16.4 0 22.6l25.4 25.4c6.2 6.2 16.4 6.2 22.6 0L152 408l31.1 33c15.1 15.1 40.9 4.4 40.9-17V312c0-13.3-10.7-24-24-24zm112-64h112c21.4 0 32.1-25.9 17-41l-33-31 99.3-99.3c6.2-6.2 6.2-16.4 0-22.6L481.9 4.7c-6.2-6.2-16.4-6.2-22.6 0L360 104l-31.1-33C313.8 55.9 288 66.6 288 88v112c0 13.3 10.7 24 24 24zm96 136l33-31.1c15.1-15.1 4.4-40.9-17-40.9H312c-13.3 0-24 10.7-24 24v112c0 21.4 25.9 32.1 41 17l31-32.9 99.3 99.3c6.2 6.2 16.4 6.2 22.6 0l25.4-25.4c6.2-6.2 6.2-16.4 0-22.6L408 360zM183 71.1L152 104 52.7 4.7c-6.2-6.2-16.4-6.2-22.6 0L4.7 30.1c-6.2 6.2-6.2 16.4 0 22.6L104 152l-33 31.1C55.9 198.2 66.6 224 88 224h112c13.3 0 24-10.7 24-24V88c0-21.3-25.9-32-41-16.9z\"><\/path><\/svg><\/div><\/div><div class=\"pbmit-ihbox-contents\">\r\n\t\t\t<h2 class=\"pbmit-element-title\">Polyvalence<\/h2>\t\t<\/div><!-- .pbmit-ihbox-contents --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4e416cc pbmit-bg-color-over-image\" data-id=\"4e416cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df78420 elementor-widget elementor-widget-pbmit_icon_heading\" data-id=\"df78420\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pbmit-ihbox pbmit-ihbox-style-16\"><div class=\"pbmit-ihbox-icon\"><div class=\"pbmit-ihbox-icon-wrapper pbmit-icon-type-icon\"><i class=\"mdi mdi-access-time\"><\/i><\/div><\/div><div class=\"pbmit-ihbox-contents\">\r\n\t\t\t<h2 class=\"pbmit-element-title\">Prise en charge rapide <\/h2>\t\t<\/div><!-- .pbmit-ihbox-contents --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8491fa5 pbmit-bg-color-over-image\" data-id=\"8491fa5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50072d2 elementor-widget elementor-widget-pbmit_icon_heading\" data-id=\"50072d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pbmit-ihbox pbmit-ihbox-style-16\"><div class=\"pbmit-ihbox-icon\"><div class=\"pbmit-ihbox-icon-wrapper pbmit-icon-type-icon\"><i class=\"pbmit-xcare-icon pbmit-xcare-icon-gesundheit-1\"><\/i><\/div><\/div><div class=\"pbmit-ihbox-contents\">\r\n\t\t\t<h2 class=\"pbmit-element-title\">Environnement agr\u00e9able et s\u00e9curis\u00e9<\/h2>\t\t<\/div><!-- .pbmit-ihbox-contents --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-09b559d pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"09b559d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c6d80c6 pbmit-bg-color-over-image\" data-id=\"c6d80c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a11a5a5 elementor-widget elementor-widget-spacer\" data-id=\"a11a5a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d56f77 pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d56f77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dec3fe4 pbmit-bg-color-over-image\" data-id=\"dec3fe4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d04ec99 elementor-widget elementor-widget-pbmit_icon_heading\" data-id=\"d04ec99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pbmit-ihbox pbmit-ihbox-style-16\"><div class=\"pbmit-ihbox-icon\"><div class=\"pbmit-ihbox-icon-wrapper pbmit-ihbox-icon-type-image\"><img decoding=\"async\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/WhatsApp_Image_2025-02-20_a_14.14.16_8b81625e-removebg-preview.png\" alt=\"Pr\u00e9cision des r\u00e9sultats\" \/><\/div><\/div><div class=\"pbmit-ihbox-contents\">\r\n\t\t\t<h2 class=\"pbmit-element-title\">Pr\u00e9cision des r\u00e9sultats\n<\/h2>\t\t<\/div><!-- .pbmit-ihbox-contents --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2f6f428 pbmit-bg-color-over-image\" data-id=\"2f6f428\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-534c120 elementor-widget elementor-widget-pbmit_icon_heading\" data-id=\"534c120\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pbmit-ihbox pbmit-ihbox-style-16\"><div class=\"pbmit-ihbox-icon\"><div class=\"pbmit-ihbox-icon-wrapper pbmit-ihbox-icon-type-image\"><img decoding=\"async\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/Mini-charte-desktop_Plan-de-travail-1-copie_Plan-de-travail-1-copie_Plan-de-travail-1-copie.png\" alt=\"Ecoute et conseil\" \/><\/div><\/div><div class=\"pbmit-ihbox-contents\">\r\n\t\t\t<h2 class=\"pbmit-element-title\">Ecoute et conseil<\/h2>\t\t<\/div><!-- .pbmit-ihbox-contents --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0a3ce0 pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0a3ce0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ff5b11 pbmit-bg-color-over-image\" data-id=\"2ff5b11\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9592ee elementor-widget elementor-widget-spacer\" data-id=\"d9592ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a2b6f9 elementor-section-full_width pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-height-default elementor-section-height-default\" data-id=\"7a2b6f9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fd3f225 pbmit-bg-color-yes pbmit-elementor-bg-color-secondary pbmit-text-color-white pbmit-bg-image-over-color\" data-id=\"fd3f225\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fedfb8 elementor-widget elementor-widget-pbmit_icon_heading\" data-id=\"6fedfb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pbmit-ihbox pbmit-ihbox-style-17\"><div class=\"pbmit-ihbox-box\">\r\n\t<div class=\"pbmit-ihbox-icon\"><div class=\"pbmit-ihbox-icon-wrapper pbmit-icon-type-icon\"><i class=\"pbmit-xcare-icon pbmit-xcare-icon-appointment\"><\/i><\/div><\/div>\t<div class=\"pbmit-ihbox-contents\">\r\n\t\t\t\t<h2 class=\"pbmit-element-title\">Vous recherchez des professionnels et des analyses m\u00e9dicales de confiance ?\n<\/h2>\t\t<div class=\"pbmit-element-heading\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t\tN\u2019h\u00e9sitez pas \u00e0 nous contacter.\r\n\t\t\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t<div class=\"pbmit-ihbox-btn\"><a href=\"\/contact\/\"><span class=\"pbmit-button-text\">Nous contactez<\/span><span class=\"pbmit-button-icon-wrapper\"><span class=\"pbmit-button-icon\"><i class=\"pbmit-base-icon-black-arrow-1\"><\/i><\/span><\/span><\/a><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e88faec pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e88faec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eecf948 pbmit-bg-color-over-image\" data-id=\"eecf948\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6979074 elementor-widget elementor-widget-spacer\" data-id=\"6979074\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-79dd816 pbmit-bg-color-yes pbmit-elementor-bg-color-white pbmit-bg-color-over-image\" data-id=\"79dd816\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f706113 elementor-widget elementor-widget-pbmit_heading\" data-id=\"f706113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"pbmit-heading-subheading pbmit-reverse-heading-yes animation-style4\"><h2 class=\"pbmit-element-title\">\r\n\t\t\t\r\n\t\t\t\tContactez Nous\n\r\n\t\t\t\r\n\t\t\t<\/h2>\r\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e144973 elementor-widget elementor-widget-shortcode\" data-id=\"e144973\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-397\"><form id=\"wpforms-form-397\" class=\"wpforms-validate wpforms-form\" data-formid=\"397\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/829\" data-token=\"34d676de21a02188019d093835ecb532\" data-token-time=\"1784153176\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-397-field_0-container\" class=\"wpforms-field wpforms-field-name wpforms-one-half wpforms-first\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-397-field_0\">Nom et pr\u00e9nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-397-field_0\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][0]\" aria-errormessage=\"wpforms-397-field_0-error\" required><\/div><div id=\"wpforms-397-field_1-container\" class=\"wpforms-field wpforms-field-email wpforms-one-half\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-397-field_1\">E-Mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-397-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" aria-errormessage=\"wpforms-397-field_1-error\" required><\/div><div id=\"wpforms-397-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-397-field_6\">T\u00e9l\u00e9phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-397-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" aria-errormessage=\"wpforms-397-field_6-error\" required><\/div><div id=\"wpforms-397-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-397-field_3\">Sujet <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-397-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-397-field_3-error\" required><\/div><div id=\"wpforms-397-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-397-field_2\">Messages <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-397-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-397-field_2-error\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-397-field-hp\" class=\"wpforms-field-label\">Message<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-397-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"397\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/lamddk.com\/en\/wp-json\/wp\/v2\/pages\/829\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-397\" class=\"wpforms-submit\" data-alt-text=\"Demande en cours d&#039;envoie...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cca8b96 elementor-section-full_width pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-height-default elementor-section-height-default\" data-id=\"cca8b96\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35599f2 pbmit-bg-color-over-image\" data-id=\"35599f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc35cad elementor-widget elementor-widget-pbmit_client_element\" data-id=\"cc35cad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pbmit_client_element.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div class=\"pbminfotech-element\r\n\t\t\tpbminfotech-element-client\t\t\tpbmit-element-client-style-1\t\t\tpbmit-element-viewtype-carousel\t\t\tpbmit-element-column-five\t\t\tpbmit-element-sticky-carousel-false\t\t\tpbmit-element-caroursel-dot-false\t\t\tpbmit-infinite-scroll-no\t\t\tpbmit-infinite-scroll-button-no\t\t\tpbminfotech-gap-default\t\t\t\t\t\t\t\t\t\"\r\n\r\n\t\t\tdata-cpt=\"client\"\r\n\t\t\tdata-totalpagination=\"2\"\r\n\t\t\tdata-style=\"1\"\r\n\t\t\tdata-show=\"14\"\r\n\t\t\tdata-columns=\"5\"\r\n\t\t\tdata-loop=\"true\"\r\n\t\t\tdata-autoplay=\"true\"\r\n\t\t\tdata-center=\"false\"\r\n\t\t\tdata-nav=\"false\"\r\n\t\t\tdata-dots=\"false\"\r\n\t\t\tdata-reverse=\"false\"\r\n\t\t\tdata-speed=\"3000\"\r\n\t\t\tdata-delay=\"4000\"\r\n\t\t\tdata-margin=\"default\"\r\n\t\t\tdata-show-portion=\"false\">\r\n\r\n\t\t\t<div class=\"pbmit-element-inner\">\r\n\t\t\r\n\r\n\t\t\r\n\t\t<div class=\"pbmit-ele-header-area\">\r\n\t\t\t\t<div class=\"pbmit-heading-subheading  animation-style4\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t<div class=\"pbmit-infinite-scroll-data\">{\"cpt\":\"client\",\"style\":\"1\",\"columns\":\"5\",\"show\":14,\"from_category\":[\"black\"],\"order\":\"DESC\",\"orderby\":\"DESC\"}<\/div>\r\n\t\t\t<div class=\"pbmit-element-posts-wrapper row multi-columns-row swiper-container\">\r\n\r\n\t\t\t\t<article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">Phillipe Morris<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2026\/04\/pm.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2026\/04\/pm.png 225w, https:\/\/lamddk.com\/wp-content\/uploads\/2026\/04\/pm-150x150.png 150w, https:\/\/lamddk.com\/wp-content\/uploads\/2026\/04\/pm-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article><article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">WeCover<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/12\/wecover.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/12\/wecover.png 225w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/12\/wecover-150x150.png 150w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/12\/wecover-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article><article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent 16 pbmit-term-109 black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">LLYOD 2<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"612\" height=\"408\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/Lloyd-Vie-1-removebg-preview.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/Lloyd-Vie-1-removebg-preview.png 612w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/Lloyd-Vie-1-removebg-preview-300x200.png 300w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/Lloyd-Vie-1-removebg-preview-18x12.png 18w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article><article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent 15 pbmit-term-108 black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">SMPI<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/6-1.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/6-1.png 225w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/6-1-150x150.png 150w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/6-1-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article><article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent 16 pbmit-term-109 black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">PIRECO<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/5.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/5.png 225w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/5-150x150.png 150w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/5-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article><article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent 17 pbmit-term-110 black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">ericsson<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/4.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/4.png 225w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/4-150x150.png 150w, https:\/\/lamddk.com\/wp-content\/uploads\/2025\/02\/4-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article><article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent 14 pbmit-term-107 black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">Client-14<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-15.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-15.png 225w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-15-150x150.png 150w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-15-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article><article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent 13 pbmit-term-106 black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">Client-03<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/3.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/3.png 225w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/3-150x150.png 150w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/3-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article><article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent 12 pbmit-term-105 black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">Client-04<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2.png 225w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-150x150.png 150w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article><article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent 11 pbmit-term-113 black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">Client-05<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-3.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-3.png 225w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-3-150x150.png 150w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-3-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article><article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent 10 pbmit-term-112 black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">Client-06<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__2_-removebg-preview.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__2_-removebg-preview.png 225w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__2_-removebg-preview-150x150.png 150w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__2_-removebg-preview-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article><article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent 9 pbmit-term-111 black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">Client-07<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-5.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-5.png 225w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-5-150x150.png 150w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-5-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article><article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent 8 pbmit-term-104 black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">Client-08<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-6.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-6.png 225w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-6-150x150.png 150w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-6-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article><article class=\"pbmit-ele pbmit-ele-client pbmit-client-style-1 col-md-20percent 7 pbmit-term-103 black pbmit-term-42  \"><div class=\"pbmit-border-wrapper\">\r\n\t<div class=\"pbmit-client-wrapper\">\r\n\t\t<h4 class=\"pbmit-hide\">Client-09<\/h4>\r\n\t\t\t\t\t\t<div class=\"pbmit-featured-img-wrapper\"><div class=\"pbmit-featured-wrapper\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-7.png\" class=\"attachment-pbmit-img-770x9999 size-pbmit-img-770x9999 wp-post-image\" alt=\"\" srcset=\"https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-7.png 225w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-7-150x150.png 150w, https:\/\/lamddk.com\/wp-content\/uploads\/2024\/11\/images__1_-removebg-preview-2-7-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div>\t\t\t<\/div>\r\n<\/div><\/article>\r\n\t\t\t<\/div> <!-- .pbmit-element-posts-wrapper -->\r\n\r\n\t\t\t\r\n\t\t\r\n\t\t\r\n\t\t\t\t\t<\/div><!-- .pbmit-element-inner -->\r\n\t\t<\/div><!-- .pbminfotech-element -->\r\n\r\n\t\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15349c0 pbmit-col-stretched-none pbmit-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15349c0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a4d1aa7 pbmit-bg-color-over-image\" data-id=\"a4d1aa7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e7cb0e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9e7cb0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Garde de nuit : +216 98 529 338 NOS PRESTATIONS. NOS PRESTATIONS. NOS PRESTATIONS . Notre laboratoire de biologie m\u00e9dicale est accr\u00e9dit\u00e9 par le Conseil Nationald\u2019Accr\u00e9ditation TUNAC sous le certificat n\u00b0 1-0124, valable du 29\/10\/2025 au 28\/10\/2030.Cette accr\u00e9ditation confirme la qualit\u00e9, la fiabilit\u00e9 et la conformit\u00e9 de nos analyses selonles normes internationales. Horaires Lundi &#8211; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-829","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/lamddk.com\/en\/wp-json\/wp\/v2\/pages\/829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamddk.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lamddk.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lamddk.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lamddk.com\/en\/wp-json\/wp\/v2\/comments?post=829"}],"version-history":[{"count":419,"href":"https:\/\/lamddk.com\/en\/wp-json\/wp\/v2\/pages\/829\/revisions"}],"predecessor-version":[{"id":4982,"href":"https:\/\/lamddk.com\/en\/wp-json\/wp\/v2\/pages\/829\/revisions\/4982"}],"wp:attachment":[{"href":"https:\/\/lamddk.com\/en\/wp-json\/wp\/v2\/media?parent=829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}